{"id":19076,"date":"2012-07-17T12:51:49","date_gmt":"2012-07-17T12:51:49","guid":{"rendered":"https:\/\/wordpress.org\/plugins-wp\/dedinomy\/"},"modified":"2012-10-31T17:57:30","modified_gmt":"2012-10-31T17:57:30","slug":"dedinomy","status":"publish","type":"plugin","link":"https:\/\/tl.wordpress.org\/plugins\/dedinomy\/","author":9852974,"comment_status":"closed","ping_status":"closed","template":"","meta":{"version":"1.1","stable_tag":"1.1","tested":"3.4.2","requires":"3.0.0","requires_php":"","requires_plugins":"","header_name":"Mes d\u00e9dicaces avec D\u00e9dinomy BETA","header_author":"Jean-Baptiste Fournot","header_description":"","assets_banners_color":"","last_updated":"2012-10-31 17:57:30","external_support_url":"","external_repository_url":"","donate_link":"http:\/\/forum.nubox.fr","header_plugin_uri":"http:\/\/forum.nubox.fr","header_author_uri":"","rating":0,"author_block_rating":0,"active_installs":10,"downloads":2833,"num_ratings":0,"support_threads":0,"support_threads_resolved":0,"author_block_count":0,"sections":["description","installation","faq","changelog"],"tags":[],"upgrade_notice":{"0.0":"<p>Nothing<\/p>"},"ratings":{"1":0,"2":0,"3":0,"4":0,"5":0},"assets_icons":[],"assets_banners":[],"assets_blueprints":{},"all_blocks":[],"tagged_versions":["1.0","1.1"],"block_files":[],"assets_screenshots":{"screenshot-1.png":{"filename":"screenshot-1.png","revision":"1539420","resolution":"1","location":"plugin","width":1466,"height":737}},"screenshots":[]},"plugin_section":[],"plugin_tags":[23081,23080,704],"plugin_category":[50],"plugin_contributors":[],"plugin_business_model":[],"class_list":["post-19076","plugin","type-plugin","status-publish","hentry","plugin_tags-dedicaces","plugin_tags-dedinomy","plugin_tags-radio","plugin_category-media","plugin_committers-jbfournot"],"banners":[],"icons":{"svg":false,"icon":"https:\/\/s.w.org\/plugins\/geopattern-icon\/dedinomy.svg","icon_2x":false,"generated":true},"screenshots":[{"src":"https:\/\/ps.w.org\/dedinomy\/trunk\/screenshot-1.png?rev=1539420","caption":""}],"raw_content":"<!--section=description-->\n<p>Vous souhaitez afficher vos d\u00e9dicaces via D\u00e9dinomy sur votre installation Wordpress, le plugin\nD\u00e9dinomy for Wordpress est fait pour vous :\nGr\u00e2ce \u00e0 notre widget, vous pouvez facilement ajouter la liste des derni\u00e8res d\u00e9dicaces en provenance de D\u00e9dinomy.\nVous n'avez plus qu'a r\u00e9adapt\u00e9 votre feuille de style pour personnaliser l'affichage des d\u00e9dicaces.<\/p>\n\n<p>Vous pouvez utiliser r\u00e9utilisez l'API d\u00e9dinomy en dehors du Plugin pour lib\u00e9rer \u00e0 100 % \nl'affichage des d\u00e9dicaces.<\/p>\n\n<!--section=installation-->\n<h4>Pr\u00e9-requis pour l'utilisation du plugin<\/h4>\n\n<p>Ce plugin n'est compatible que pour les versions sup\u00e9rieurs \u00e0 4.0.0 de D\u00e9dinomy.\nPour v\u00e9rifier votre version, connectez-vous \u00e0 votre installation D\u00e9dinomy, \u00e0 la rubrique Mon compte D\u00e9dinomy. Le num\u00e9ro de version vous sera indiqu\u00e9.\nPensez \u00e0 mettre \u00e0 jour votre version D\u00e9dinomy ainsi que celle de Wordpress avant l'installation du Plugin<\/p>\n\n<h4>Installation<\/h4>\n\n<ol>\n<li>Ajouter <code>dedinomy<\/code> dans le dossier <code>\/wp-content\/plugins\/<\/code><\/li>\n<li>Activer le plugin dans le menu Plugins de Wordpress<\/li>\n<li>Activer le widget<\/li>\n<\/ol>\n\n<!--section=faq-->\n<dl>\n<dt>Rien ne fonctionne !<\/dt>\n<dd><p>Simplifions la t\u00e2che, si rien ne fonctionne : \nV\u00e9rifiez tout d'abord que votre version de D\u00e9dinomy est \u00e0 jour (Version 4.0.0 et sup\u00e9rieurs);\nV\u00e9rifiez la pr\u00e9sence du fichier api.php sur votre dossier d'installation\nV\u00e9rifiez en d\u00e9sactivant le plugin si l'erreur persiste. Dans ce cas, celle ci provient d'un autre plugin<\/p><\/dd>\n<dt>Questions et suggestions<\/dt>\n<dd><p>Connectez-vous sur le forum Nubox pour pouvoir nous donner vos retours sur cette application<\/p><\/dd>\n\n<\/dl>\n\n<!--section=changelog-->\n<h4>1.1<\/h4>\n\n<ul>\n<li>Correction bug pour versions PHP ne prenant en charge Files_include via Curl<\/li>\n<\/ul>\n\n<h4>1.0<\/h4>\n\n<ul>\n<li>MISE A JOUR PROCHAINE A PREVOIR FIN AOUT<\/li>\n<li>Widget permettant d'afficher les derni\u00e8res d\u00e9dicaces<\/li>\n<li>Traduction en anglais si la langue par d\u00e9faut de Wordpress est l'anglais.<\/li>\n<\/ul>","raw_excerpt":"Avec le plugin D\u00e9dinomy, afficher toutes vos d\u00e9dicaces sur votre installation Wordpress en quelques secondes.","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/tl.wordpress.org\/plugins\/wp-json\/wp\/v2\/plugin\/19076","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tl.wordpress.org\/plugins\/wp-json\/wp\/v2\/plugin"}],"about":[{"href":"https:\/\/tl.wordpress.org\/plugins\/wp-json\/wp\/v2\/types\/plugin"}],"replies":[{"embeddable":true,"href":"https:\/\/tl.wordpress.org\/plugins\/wp-json\/wp\/v2\/comments?post=19076"}],"author":[{"embeddable":true,"href":"https:\/\/tl.wordpress.org\/plugins\/wp-json\/wporg\/v1\/users\/jbfournot"}],"wp:attachment":[{"href":"https:\/\/tl.wordpress.org\/plugins\/wp-json\/wp\/v2\/media?parent=19076"}],"wp:term":[{"taxonomy":"plugin_section","embeddable":true,"href":"https:\/\/tl.wordpress.org\/plugins\/wp-json\/wp\/v2\/plugin_section?post=19076"},{"taxonomy":"plugin_tags","embeddable":true,"href":"https:\/\/tl.wordpress.org\/plugins\/wp-json\/wp\/v2\/plugin_tags?post=19076"},{"taxonomy":"plugin_category","embeddable":true,"href":"https:\/\/tl.wordpress.org\/plugins\/wp-json\/wp\/v2\/plugin_category?post=19076"},{"taxonomy":"plugin_contributors","embeddable":true,"href":"https:\/\/tl.wordpress.org\/plugins\/wp-json\/wp\/v2\/plugin_contributors?post=19076"},{"taxonomy":"plugin_business_model","embeddable":true,"href":"https:\/\/tl.wordpress.org\/plugins\/wp-json\/wp\/v2\/plugin_business_model?post=19076"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}